{"id":424,"date":"2025-04-26T11:45:14","date_gmt":"2025-04-26T11:45:14","guid":{"rendered":"https:\/\/tino.batlledigital.com\/?post_type=cursos&#038;p=424"},"modified":"2026-07-20T10:24:46","modified_gmt":"2026-07-20T10:24:46","slug":"proceso-wang","status":"publish","type":"cursos","link":"https:\/\/tinoprat.com\/en\/cursos\/proceso-wang\/","title":{"rendered":"Proceso Wang"},"content":{"rendered":"<h2>Proceso Wang \u00ab7 D\u00edas para toda la vida\u00bb<\/h2>\n<p>Opci\u00f3n de realizarlo en dos fines de semana o bien 7 d\u00edas seguidos<\/p>\n<p><b>\u00bfPor qu\u00e9 el curso WANG-MINDFULNESS puede ayudarme?<\/b><\/p>\n<p>El proceso Wang-Mindfulness \u201c7 d\u00edas para toda la vida\u201d, es un curso de 7 d\u00edas en los que vives una apasionantes inmersi\u00f3n, que te ayuda a reconectar con tu verdadera esencia, d\u00e1ndote las herramientas para alcanzar la felicidad, que siempre ha estado dentro de ti. Este curso de autoconocimiento te dar\u00e1 toda la fuerza para dissenyar la vida que realmente quieres, desde la plenitud, la serenidad interior \u00a0y la calma mental.<\/p>\n<p>Nuestra vida est\u00e1 en manos de nuestra reactividad emocional; nuestros sentimientos se producen autom\u00e1ticamente, sin que seamos conscientes de ello. En torno a los 7 a\u00f1os de edad y de manera inconsciente se configura nuestro Gui\u00f3n de vida, en funci\u00f3n de las experiencias emocionales que vivimos y de las estrategias que adoptamos para sobrellevarlas.<\/p>\n<p>En nuestra vida cotidiana adulta, seguimos utilizando los mismos patrones reactivos a pesar de que ya est\u00e1n caducos, lo que castra nuestra espontaneidad, nos genera ansiedad, estr\u00e9s, falta de motivaci\u00f3n, mal humor, cansancio, dolencias f\u00edsicas, sensaci\u00f3n de vac\u00edo, y un alejamiento cada vez mayor de nuestra verdadera esencia.<\/p>\n<p><strong>\u00bfQu\u00e9 se obtiene?<\/strong><\/p>\n<p>Consciencia plena (Mindfulness).\u00a0Recuperas el sentido de tu vida y empiezas a vivir <em>una vida de sentido<\/em>.<\/p>\n<p>Ganas Autoaceptaci\u00f3n, sanaci\u00f3n de la Autoestima, mejora de la Autonom\u00eda y \u00a0un grado de Autenticidad como nunca antes.<\/p>\n<p>Obtienes herramientas concretas y sencillas para sanar tu emocionalidad, sin dependencias ni invalidaciones. Recuperas la habilidad innata de transformar tus sue\u00f1os en realidades, dejando a un lado la ansiedad, la depresi\u00f3n, la irritabilidad, los desajustes del sue\u00f1o, etc\u2026<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfA qui\u00e9n se dirige?<\/strong><\/p>\n<p>A cualquier persona de m\u00e1s de 18 a\u00f1os interesada en crecer, resolver o mejorar su vida, conociendo un modelo para alcanzar la felicidad.<\/p>\n<p>NOTA IMPORTANTE: nuestro m\u00e9todo NO tiene las respuestas a tus preguntas, sino que s\u00f3lo es una forma para que t\u00fa puedas encontrarlas por ti mismo. Nosotros te mostramos un camino que s\u00f3lo t\u00fa puedes recorrer.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ITINERARIO<\/strong><\/p>\n<p><b>-CUESTIONARIO WANG.<\/b> Se rellena ON LINE y\u00a0permite un diagn\u00f3stico sobre tu estado emocional. Los resultados obtenidos se contrastan en una reuni\u00f3n de 50 minutos con nosotros. Solic\u00edtalo\u00a0<strong>aqu\u00ed.<\/strong><\/p>\n<p><b>-PRESENTACI\u00d3N.\u00a0<\/b>Abierta a todas las personas que quieran conocernos, para comprender el funcionamiento del Ser Humano y conocer el proceso a trav\u00e9s de\u00a0ex alumnos.<\/p>\n<p>Si se tomara la decisi\u00f3n de realizar el Proceso Wang, lo siguientes pasos ser\u00edan:<\/p>\n<p><b>1-MATERIAL \u00a0A RELLENAR ANTES DE ENTRAR EN CURSO<\/b><\/p>\n<p><b>2-INMERSI\u00d3N <\/b><strong>en el Curso<\/strong><b> \u201c7 d\u00edas para toda la vida\u201d.<\/b><\/p>\n<p><b>3-CONSOLIDACI\u00d3N. <\/b><\/p>\n<p><b>4-CIERRE.<\/b><\/p>\n<p><b>5-REVISI\u00d3N A LOS 3 MESES<\/b><\/p>","protected":false},"parent":0,"template":"","tipo-de-curso":[10],"class_list":["post-424","cursos","type-cursos","status-publish","hentry","tipo-de-curso-particular"],"_links":{"self":[{"href":"https:\/\/tinoprat.com\/en\/wp-json\/wp\/v2\/cursos\/424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tinoprat.com\/en\/wp-json\/wp\/v2\/cursos"}],"about":[{"href":"https:\/\/tinoprat.com\/en\/wp-json\/wp\/v2\/types\/cursos"}],"wp:attachment":[{"href":"https:\/\/tinoprat.com\/en\/wp-json\/wp\/v2\/media?parent=424"}],"wp:term":[{"taxonomy":"tipo-de-curso","embeddable":true,"href":"https:\/\/tinoprat.com\/en\/wp-json\/wp\/v2\/tipo-de-curso?post=424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}